{"id":25,"date":"2023-03-05T10:39:43","date_gmt":"2023-03-05T10:39:43","guid":{"rendered":"https:\/\/energy-splendor.com\/?page_id=25"},"modified":"2025-10-30T07:48:52","modified_gmt":"2025-10-30T07:48:52","slug":"about","status":"publish","type":"page","link":"https:\/\/energy-splendor.com\/es_ec\/about\/","title":{"rendered":"Acerca de"},"content":{"rendered":"<section class=\"section\" id=\"section_1968912703\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row align-equal\"  id=\"row-653440338\">\n\n\t<div id=\"col-817183149\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1793356469\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1793356469 {\n  padding-top: 5px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1814873746\" class=\"text\">\n\t\t\n<h2>INFORMACI\u00d3N DE LA EMPRESA<\/h2>\n\t\t\n<style>\n#text-1814873746 {\n  font-size: 1rem;\n}\n@media (min-width:550px) {\n  #text-1814873746 {\n    font-size: 1rem;\n  }\n}\n@media (min-width:850px) {\n  #text-1814873746 {\n    font-size: 1.4rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-512579090\" class=\"gap-element clearfix hide-for-small\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-512579090 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n<p data-start=\"159\" data-end=\"898\">Energy Splendor es un fabricante y proveedor l\u00edder de estaciones de recarga para veh\u00edculos el\u00e9ctricos (VE), que ofrece una amplia gama de cargadores de CA y CC, incluidos cargadores r\u00e1pidos de Nivel 1, Nivel 2 y Nivel 3. Nuestros cargadores cubren un rango de potencia de 3,5 kW a 1140 kW, dise\u00f1ados para satisfacer las diversas necesidades de recarga de hogares, edificios comerciales, dep\u00f3sitos de flotas y redes p\u00fablicas de recarga. Con un s\u00f3lido equipo de investigaci\u00f3n y desarrollo, capacidades avanzadas de ingenier\u00eda y tecnolog\u00eda innovadora de recarga inteligente, ofrecemos soluciones de recarga de VE confiables, eficientes y seguras. Energy Splendor combina un dise\u00f1o de vanguardia, una fabricaci\u00f3n de alta calidad y est\u00e1ndares globales para apoyar el crecimiento de la infraestructura de veh\u00edculos el\u00e9ctricos en todo el mundo.<\/p>\n\t<div id=\"gap-1541424500\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1541424500 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/es_ec\/contact\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>Solicita una consulta gratuita<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-817183149 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-817183149 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-817183149 > .col-inner {\n    padding: 0px 20px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1344475783\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_583349632\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover box-shadow-1 box-shadow-5-hover dark\" style=\"padding-top:70%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/China-Electric-Vehicle-Charging-Station-Manufacturer-Factory-Warehouse.webp\" class=\"attachment-original size-original\" alt=\"China EV charging station manufacturing factory with warehouse and production lines\" srcset=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/China-Electric-Vehicle-Charging-Station-Manufacturer-Factory-Warehouse.webp 900w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/China-Electric-Vehicle-Charging-Station-Manufacturer-Factory-Warehouse-300x200.webp 300w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/China-Electric-Vehicle-Charging-Station-Manufacturer-Factory-Warehouse-768x512.webp 768w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/China-Electric-Vehicle-Charging-Station-Manufacturer-Factory-Warehouse-18x12.webp 18w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/China-Electric-Vehicle-Charging-Station-Manufacturer-Factory-Warehouse-600x400.webp 600w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_583349632 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1344475783 > .col-inner {\n  padding: 0px 0px 0px 0px;\n  border-radius: 8px;\n}\n@media (min-width:550px) {\n  #col-1344475783 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-1344475783 > .col-inner {\n    padding: 0px 0px 0px 20px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-61652855\">\n\n\t<div id=\"col-857272327\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2026026676\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Energy-Splendor-EV-Charging-Station-Factory-Warehouse-\u2013-ACDC-Chargers-3.5\u20131140-kW-Level-1\u20133-OEMODM-Wholesale-Global-Distribution.webp\" class=\"attachment-large size-large\" alt=\"Energy Splendor EV charging station factory and warehouse producing Level 1, Level 2, and Level 3 AC\/DC chargers with OEM\/ODM, wholesale, and global distribution\" srcset=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Energy-Splendor-EV-Charging-Station-Factory-Warehouse-\u2013-ACDC-Chargers-3.5\u20131140-kW-Level-1\u20133-OEMODM-Wholesale-Global-Distribution.webp 900w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Energy-Splendor-EV-Charging-Station-Factory-Warehouse-\u2013-ACDC-Chargers-3.5\u20131140-kW-Level-1\u20133-OEMODM-Wholesale-Global-Distribution-300x200.webp 300w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Energy-Splendor-EV-Charging-Station-Factory-Warehouse-\u2013-ACDC-Chargers-3.5\u20131140-kW-Level-1\u20133-OEMODM-Wholesale-Global-Distribution-768x512.webp 768w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Energy-Splendor-EV-Charging-Station-Factory-Warehouse-\u2013-ACDC-Chargers-3.5\u20131140-kW-Level-1\u20133-OEMODM-Wholesale-Global-Distribution-18x12.webp 18w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Energy-Splendor-EV-Charging-Station-Factory-Warehouse-\u2013-ACDC-Chargers-3.5\u20131140-kW-Level-1\u20133-OEMODM-Wholesale-Global-Distribution-600x400.webp 600w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2026026676 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-420871528\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 data-start=\"116\" data-end=\"196\"><span style=\"font-size: 150%;\"><strong data-start=\"120\" data-end=\"196\"><span class=\"_fadeIn_pfttw_8\">Cargador EV\u00a0<\/span><span class=\"_fadeIn_pfttw_8\">Fabricaci\u00f3n<\/span><\/strong><\/span><\/h2>\n<p>Nuestra f\u00e1brica est\u00e1 ubicada en Yueqing, provincia de Zhejiang, China, un centro de excelencia en la fabricaci\u00f3n de productos el\u00e9ctricos. Con una extensi\u00f3n de miles de metros cuadrados, nuestras instalaciones cuentan con l\u00edneas de producci\u00f3n de \u00faltima generaci\u00f3n, sistemas de ensamblaje automatizados y equipos de prueba avanzados, lo que garantiza una producci\u00f3n constante y de alta calidad. Con un valor de producci\u00f3n anual que supera los 500 millones de RMB, Energy Splendor tiene la capacidad de fabricar grandes vol\u00famenes de cargadores para veh\u00edculos el\u00e9ctricos en m\u00faltiples especificaciones, desde cargadores compactos y port\u00e1tiles de Nivel 1 hasta estaciones de carga r\u00e1pida de CC de Nivel 3 de alta potencia. Nuestra f\u00e1brica cumple con estrictos sistemas de gesti\u00f3n de calidad ISO, y cada producto se somete a rigurosas inspecciones, pruebas de rendimiento y verificaciones de seguridad antes de su env\u00edo.<\/p>\n<a href=\"\/es_ec\/contact\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>Solicita una consulta gratuita<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1968912703 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n@media (min-width:550px) {\n  #section_1968912703 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n@media (min-width:850px) {\n  #section_1968912703 {\n    padding-top: 80px;\n    padding-bottom: 80px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\t<section class=\"section\" id=\"section_1584183662\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-2018287032\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2018287032 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1102870759\">\n\n\t<div id=\"col-1960222214\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2894478876\" class=\"text\">\n\t\t\n<h2 data-start=\"111\" data-end=\"138\"><span style=\"color: #000000;\"><strong data-start=\"114\" data-end=\"136\">Nuestras calificaciones<\/strong><\/span><\/h2>\n\t\t\n<style>\n#text-2894478876 {\n  font-size: 1.35rem;\n  text-align: center;\n  color: rgb(255,255,255);\n}\n#text-2894478876 > * {\n  color: rgb(255,255,255);\n}\n<\/style>\n\t<\/div>\n\t\n<p data-start=\"139\" data-end=\"643\"><span style=\"color: #000000;\">Energy Splendor es un l\u00edder mundial de confianza en la producci\u00f3n de estaciones de carga de alta calidad para veh\u00edculos el\u00e9ctricos (VE), que ofrece una gama completa de cargadores de CA y CC, incluyendo cargadores de Nivel 1, Nivel 2 y Nivel 3, cargadores port\u00e1tiles, unidades de pared, cargadores de pedestal y estaciones de carga de CC de alta potencia con m\u00faltiples puntos de carga. Nuestros cargadores cuentan con un rango de potencia que va desde los 3,5 kW hasta los 1140 kW, lo que permite su uso en diversas aplicaciones en redes de carga residenciales, comerciales, de flotas y p\u00fablicas.<\/span><\/p>\n<p data-start=\"645\" data-end=\"1055\"><span style=\"color: #000000;\">Contamos con prestigiosas certificaciones, entre ellas CE, UL, IEC e ISO, lo que garantiza que nuestros cargadores cumplan con los m\u00e1s altos est\u00e1ndares de seguridad, confiabilidad y rendimiento. Nuestras instalaciones de fabricaci\u00f3n de \u00faltima generaci\u00f3n en Yueqing, Zhejiang, China, equipadas con l\u00edneas de producci\u00f3n avanzadas, ensamblaje automatizado y un riguroso control de calidad, garantizan soluciones de recarga para veh\u00edculos el\u00e9ctricos eficientes, duraderas y listas para el mercado.<\/span><\/p>\n<p data-start=\"1057\" data-end=\"1366\"><span style=\"color: #000000;\">Ya sea que necesites cargadores personalizados, servicios OEM\/ODM o pedidos al por mayor, Energy Splendor ofrece soluciones flexibles para distribuidores globales, operadores de flotas, propiedades comerciales y proyectos de infraestructura para veh\u00edculos el\u00e9ctricos, proporcionando estaciones de carga inteligentes, confiables y de alto rendimiento en todo el mundo.<\/span><\/p>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1960222214 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1055427965\">\n\n\t<div id=\"col-937409567\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<a href=\"\/es_ec\/shop\/\" class=\"button white\"  style=\"border-radius:99px;\">\n    <span>Personaliza tu Ev CHARGER ahora<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-937409567 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1584183662 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n#section_1584183662 .section-bg-overlay {\n  background-color: #3ab54b;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1636314960\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-810634434\">\n\n\t<div id=\"col-599242459\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1052078742\" class=\"gap-element clearfix hide-for-medium\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1052078742 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-599242459 > .col-inner {\n  margin: 0px 0px -20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-equal\" style=\"max-width:1400px\" id=\"row-744711513\">\n\n\t<div id=\"col-1326346067\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1467787371\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-1 box-shadow-5-hover dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Global-EV-Charging-Solutions-Factory-\u2013-OEMODM-Wholesale.webp\" class=\"attachment-original size-original\" alt=\"Energy Splendor global EV charging solutions factory, offering AC and DC chargers from 3.5 kW to 1140 kW, CE &amp; RoHS certified, supporting OEM\/ODM, wholesale, and international distribution\" srcset=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Global-EV-Charging-Solutions-Factory-\u2013-OEMODM-Wholesale.webp 900w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Global-EV-Charging-Solutions-Factory-\u2013-OEMODM-Wholesale-300x200.webp 300w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Global-EV-Charging-Solutions-Factory-\u2013-OEMODM-Wholesale-768x512.webp 768w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Global-EV-Charging-Solutions-Factory-\u2013-OEMODM-Wholesale-18x12.webp 18w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/10\/Global-EV-Charging-Solutions-Factory-\u2013-OEMODM-Wholesale-600x400.webp 600w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1467787371 {\n  width: 100%;\n}\n@media (min-width:550px) {\n  #image_1467787371 {\n    width: 100%;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1326346067 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1326346067 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-1326346067 > .col-inner {\n    padding: 0px 30px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-58287278\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-666253916\" class=\"text\">\n\t\t\n<h2>Ventas y servicios a nivel mundial<\/h2>\n\t\t\n<style>\n#text-666253916 {\n  font-size: 1rem;\n}\n@media (min-width:550px) {\n  #text-666253916 {\n    font-size: 1rem;\n  }\n}\n@media (min-width:850px) {\n  #text-666253916 {\n    font-size: 1.3rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1984636572\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1984636572 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n<p>Los cargadores Energy Splendor est\u00e1n dise\u00f1ados tanto para el mercado nacional como para el internacional, y ofrecen soluciones para clientes residenciales, comerciales e industriales. Ofrecemos suministro directo de f\u00e1brica, pedidos al por mayor y personalizaci\u00f3n OEM\/ODM, lo que garantiza que nuestros clientes reciban productos de alta calidad, precios competitivos y apoyo profesional. Nuestra red de servicios incluye asistencia t\u00e9cnica, orientaci\u00f3n para la instalaci\u00f3n, soporte de mantenimiento y soluciones llave en mano, lo que permite a los clientes instalar estaciones de carga para veh\u00edculos el\u00e9ctricos de manera r\u00e1pida y confiable. Al combinar tecnolog\u00eda inteligente, un dise\u00f1o robusto y un soporte integral, los cargadores Energy Splendor ayudan a nuestros socios a optimizar el uso de la energ\u00eda y la eficiencia operativa.<\/p>\n\t<div id=\"gap-1272152287\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1272152287 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/es_ec\/contact\/\" class=\"button primary\"  style=\"border-radius:99px;\">\n    <span>\u00danete a nosotros ahora<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-58287278 > .col-inner {\n  padding: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-58287278 > .col-inner {\n    padding: 0px 0px 0px 0px;\n  }\n}\n@media (min-width:850px) {\n  #col-58287278 > .col-inner {\n    padding: 0px 90px 0px 30px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-1091178508\">\n\n\t<div id=\"col-1091184975\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-782523734\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-782523734 {\n  padding-top: 0px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1636314960 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1636314960 {\n    padding-top: 0px;\n    padding-bottom: 0px;\n  }\n}\n@media (min-width:850px) {\n  #section_1636314960 {\n    padding-top: 50px;\n    padding-bottom: 50px;\n  }\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About - 3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-splendor.com\/es_ec\/about\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About - 3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-splendor.com\/es_ec\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-30T07:48:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/about\\\/\",\"url\":\"https:\\\/\\\/energy-splendor.com\\\/about\\\/\",\"name\":\"About - 3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/#website\"},\"datePublished\":\"2023-03-05T10:39:43+00:00\",\"dateModified\":\"2025-10-30T07:48:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/about\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/energy-splendor.com\\\/about\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/about\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/energy-splendor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/#website\",\"url\":\"https:\\\/\\\/energy-splendor.com\\\/\",\"name\":\"3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor\",\"description\":\"Leading EV Charger Manufacturer &amp; Supplier in China \u2014 Global Supply, Customization &amp; Wholesale Service for AC &amp; DC Charging Solutions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/energy-splendor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acerca de - Fabricante de cargadores para veh\u00edculos el\u00e9ctricos de 3,5 kW a 900 kW | Estaciones de carga port\u00e1tiles, de pared y de carga r\u00e1pida de CC | Energy Splendor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-splendor.com\/es_ec\/about\/","og_locale":"es_ES","og_type":"article","og_title":"About - 3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor","og_url":"https:\/\/energy-splendor.com\/es_ec\/about\/","og_site_name":"3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor","article_modified_time":"2025-10-30T07:48:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energy-splendor.com\/about\/","url":"https:\/\/energy-splendor.com\/about\/","name":"Acerca de - Fabricante de cargadores para veh\u00edculos el\u00e9ctricos de 3,5 kW a 900 kW | Estaciones de carga port\u00e1tiles, de pared y de carga r\u00e1pida de CC | Energy Splendor","isPartOf":{"@id":"https:\/\/energy-splendor.com\/#website"},"datePublished":"2023-03-05T10:39:43+00:00","dateModified":"2025-10-30T07:48:52+00:00","breadcrumb":{"@id":"https:\/\/energy-splendor.com\/about\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-splendor.com\/about\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energy-splendor.com\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-splendor.com\/"},{"@type":"ListItem","position":2,"name":"About"}]},{"@type":"WebSite","@id":"https:\/\/energy-splendor.com\/#website","url":"https:\/\/energy-splendor.com\/","name":"Fabricante de cargadores para veh\u00edculos el\u00e9ctricos de 3,5 kW a 900 kW | Estaciones de carga port\u00e1tiles, de pared y de carga r\u00e1pida de CC | Energy Splendor","description":"Fabricante y proveedor l\u00edder de cargadores para veh\u00edculos el\u00e9ctricos en China: suministro global, personalizaci\u00f3n y servicio mayorista de soluciones de carga de CA y CC.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-splendor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":6,"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":1678,"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/pages\/25\/revisions\/1678"}],"wp:attachment":[{"href":"https:\/\/energy-splendor.com\/es_ec\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}