{"id":1861,"date":"2025-12-12T09:21:04","date_gmt":"2025-12-12T09:21:04","guid":{"rendered":"https:\/\/energy-splendor.com\/?post_type=product&#038;p=1861"},"modified":"2025-12-24T09:44:48","modified_gmt":"2025-12-24T09:44:48","slug":"powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module","status":"publish","type":"product","link":"https:\/\/energy-splendor.com\/es_cl\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/","title":{"rendered":"M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos PowerCore de 30 kW: m\u00f3dulo de potencia de carga r\u00e1pida de alta eficiencia"},"content":{"rendered":"<h2 data-start=\"348\" data-end=\"469\"><strong data-start=\"352\" data-end=\"467\">M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW: soluci\u00f3n de alimentaci\u00f3n de alta eficiencia para carga r\u00e1pida de CC en estaciones de carga comerciales para veh\u00edculos el\u00e9ctricos<\/strong><\/h2>\n<p data-start=\"470\" data-end=\"979\">A medida que la adopci\u00f3n mundial de los veh\u00edculos el\u00e9ctricos sigue aceler\u00e1ndose, la demanda de tecnolog\u00eda de carga r\u00e1pida de corriente continua (CC) de alto rendimiento est\u00e1 creciendo m\u00e1s r\u00e1pido que nunca. Para respaldar la infraestructura comercial de recarga de veh\u00edculos el\u00e9ctricos, las estaciones de recarga p\u00fablicas ultrarr\u00e1pidas, las redes de recarga en autopistas y los sistemas modulares de recarga de corriente continua, Energysplendor se enorgullece de presentar el m\u00f3dulo de recarga de corriente continua para veh\u00edculos el\u00e9ctricos de 30 kW: un m\u00f3dulo de potencia de recarga de corriente continua de 30 kW de \u00faltima generaci\u00f3n dise\u00f1ado para ofrecer alta eficiencia, confiabilidad a largo plazo y despliegue comercial a nivel mundial.<\/p>\n<p data-start=\"981\" data-end=\"1430\">Este m\u00f3dulo de carga r\u00e1pida para veh\u00edculos el\u00e9ctricos est\u00e1 dise\u00f1ado espec\u00edficamente para fabricantes de cargadores de veh\u00edculos el\u00e9ctricos, proveedores de equipos de carga (EVSE), fabricantes de gabinetes de carga y operadores de estaciones de carga que necesitan un m\u00f3dulo de potencia de carga r\u00e1pida de corriente continua (CC) que sea compacto, estable, escalable y rentable. Ya sea que se utilice como una sola unidad o en configuraciones en paralelo de hasta 60 m\u00f3dulos, es el n\u00facleo de potencia ideal para construir sistemas de carga de corriente continua de 30 kW, 60 kW, 120 kW, 180 kW, 240 kW, 360 kW e incluso de nivel de megavatios.<\/p>\n<p data-start=\"1432\" data-end=\"1794\">Dise\u00f1ado con refrigeraci\u00f3n por aire forzado, consumo ultrabajo en modo de espera, salida de corriente continua de amplio rango y protecci\u00f3n avanzada de m\u00faltiples niveles, este m\u00f3dulo de cargador comercial para veh\u00edculos el\u00e9ctricos ofrece un rendimiento excepcional en diversas aplicaciones en Brasil, Argentina, EE. UU., Canad\u00e1, M\u00e9xico, Venezuela, Australia, Alemania, Rusia, Sud\u00e1frica, los Emiratos \u00c1rabes Unidos y m\u00e1s de 50 mercados de todo el mundo.<\/p>\n<h2 data-start=\"1981\" data-end=\"2011\"><strong>Especificaciones t\u00e9cnicas<\/strong><\/h2>\n<table width=\"1154\">\n<tbody>\n<tr>\n<td colspan=\"2\" width=\"548\">Art\u00edculo<\/td>\n<td width=\"605\">Especificaciones<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"8\" width=\"196\">B\u00e1sico<br \/>\nEspecificaciones<\/td>\n<td width=\"351\">Dimensiones<\/td>\n<td width=\"605\">\u00a085 mm (alto) \u00d7 360 mm (ancho) \u00d7 459 mm (profundidad)<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Peso<\/td>\n<td width=\"605\">\u00a0\u226420 kg<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Eficiencia (a plena carga)<\/td>\n<td width=\"605\">\u00a0&gt;95,5%<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Consumo de energ\u00eda en modo de espera<\/td>\n<td width=\"605\">\u00a0&lt;13W<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Modo de enfriamiento<\/td>\n<td width=\"605\">\u00a0Enfriamiento por aire forzado<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Protocolo de bus de comunicaciones<\/td>\n<td width=\"605\">\u00a0Bus CAN<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">N\u00famero de m\u00f3dulos en paralelo<\/td>\n<td width=\"605\">\u00a0\u226460 unidades<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Indicador<\/td>\n<td width=\"605\">\u00a0Verde: funcionamiento normal Amarillo: alarma Rojo: falla<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\" width=\"196\">Entrada<\/p>\n<p>Caracter\u00edsticas<\/td>\n<td width=\"351\">Voltaje de entrada<\/td>\n<td width=\"605\">\u00a0285 V CA - 475 V CA, trif\u00e1sico + toma de tierra de protecci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Corriente de entrada<\/td>\n<td width=\"605\">\u00a0&lt;80A<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Frecuencia de la red el\u00e9ctrica<\/td>\n<td width=\"605\">\u00a045 Hz a 65 Hz<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Factor de potencia<\/td>\n<td width=\"605\">\u00a0\u22650,99<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">ITH D<\/td>\n<td width=\"605\">\u00a0\u22645%<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"7\" width=\"196\">Salida<\/p>\n<p>Caracter\u00edstica<\/td>\n<td width=\"351\">Potencia de salida<\/td>\n<td width=\"605\">\u00a030 kW a un voltaje de salida \u2265 300 Vcc<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Rango de voltaje<\/td>\n<td width=\"605\">\u00a0100 V CC a 1000 V CC, valor predeterminado: 200 V CC<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Rango actual<\/td>\n<td width=\"605\">\u00a00 A ~ 133,3 A<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Precisi\u00f3n de la tensi\u00f3n estabilizada<\/td>\n<td width=\"605\">\u00a0\u2264\u00b10,5%<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Precisi\u00f3n de la corriente estabilizada<\/td>\n<td width=\"605\">\u00a0\u2264\u00b11%<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Desequilibrio en el reparto de corriente<\/td>\n<td width=\"605\">\u00a0\u2264\u00b13%<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Coeficiente del valor m\u00e1ximo de la tensi\u00f3n de ondulaci\u00f3n<\/td>\n<td width=\"605\">\u00a0\u22641%<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"5\" width=\"196\">Medio ambiente<br \/>\nEspecificaciones<\/td>\n<td width=\"351\">Temperatura de funcionamiento<\/td>\n<td width=\"605\">\u00a0-40 \u2103 a +75 \u2103; reducci\u00f3n de la potencia de salida a temperaturas superiores a 55 \u2103<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Temperatura de almacenamiento<\/td>\n<td width=\"605\">-40 \u2103 a +2575 \u2103<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Humedad relativa<\/td>\n<td width=\"605\">\u00a0\u226495%RH, sin condensaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Altitud<\/td>\n<td width=\"605\">\u00a0\u22642000 m: potencia m\u00e1xima; &gt;1000 m: la temperatura de funcionamiento disminuye 1 \u2103 por cada 100 m adicionales.<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">MTBF<\/td>\n<td width=\"605\">\u00a0&gt;500 000 horas<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"4\" width=\"196\">Protecci\u00f3n<\/p>\n<p>Especificaciones<\/td>\n<td width=\"351\">Protecci\u00f3n contra sobretensi\u00f3n y subtensi\u00f3n de entrada<\/td>\n<td width=\"605\">\u00a0Recuperaci\u00f3n autom\u00e1tica tras un corte de energ\u00eda<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Protecci\u00f3n contra sobretensi\u00f3n de salida<\/td>\n<td width=\"605\">\u00a0Recuperaci\u00f3n manual tras un apag\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">\u00a0Protecci\u00f3n contra sobrecorriente y cortocircuito<\/td>\n<td width=\"605\">\u00a0Recuperaci\u00f3n manual tras un apag\u00f3n<\/td>\n<\/tr>\n<tr>\n<td width=\"351\">Protecci\u00f3n contra sobrecalentamiento<\/td>\n<td width=\"605\">\u00a0Recuperaci\u00f3n autom\u00e1tica tras un corte de energ\u00eda<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n  <div class=\"banner has-hover\" id=\"banner-238855931\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill\"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1853846913\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\" style=\"text-align: left;\"><span style=\"color: #000000;\"><strong data-start=\"56\" data-end=\"114\">M\u00f3dulo cargador de CC para veh\u00edculos el\u00e9ctricos de 30 kW (unidad de potencia de alta eficiencia)<\/strong><\/span><\/h2>\n<p style=\"text-align: left;\" data-start=\"108\" data-end=\"677\"><span style=\"color: #000000;\"><strong>El m\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW de Energy Splendor es una unidad de potencia de alta eficiencia, compacta y escalable, dise\u00f1ada para cargadores r\u00e1pidos comerciales de Nivel 3. Dise\u00f1ado para integrarse en sistemas de carga de 60 kW, 120 kW, 180 kW, 240 kW y 360 kW, ofrece una salida de corriente continua estable, amplia adaptabilidad de entrada y un control preciso de voltaje y corriente. Con una eficiencia superior al 95,51 TP3T, comunicaci\u00f3n CAN, enfriamiento por aire forzado y funciones de protecci\u00f3n completas, este m\u00f3dulo garantiza un funcionamiento confiable en estaciones de carga p\u00fablicas, dep\u00f3sitos de flotas, estacionamientos comerciales y redes de carga en autopistas.<\/strong><\/span><\/p>\n<a href=\"\/es_cl\/contact\/\" class=\"button primary\"  style=\"border-radius:10px;\">\n    <span>Solicite una cotizaci\u00f3n personalizada<\/span>\n  <\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1853846913 {\n  width: 85%;\n}\n#text-box-1853846913 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-238855931 {\n  padding-top: 400px;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-627828313\">\n\n\t<div id=\"col-278683643\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1272876088\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component.webp\" class=\"attachment-large size-large\" alt=\"TurboVolt 30kW DC Charging Power Module by Energysplendor, commercial EV charger component for global manufacturers, wholesale supply, and OEM customization.\" srcset=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component.webp 800w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component-300x300.webp 300w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component-150x150.webp 150w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component-768x768.webp 768w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component-12x12.webp 12w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component-600x600.webp 600w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/TurboVolt-30kW-DC-Charging-Power-Module-\u2013-Commercial-EV-Charger-Component-100x100.webp 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1272876088 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1639101440\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1972299753\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit.webp\" class=\"attachment-large size-large\" alt=\"RapidCharge 30kW EV DC Charger Module by Energysplendor, high-power fast charging unit for commercial EV charger manufacturers, global wholesale and customization.\" srcset=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit.webp 800w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit-300x300.webp 300w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit-150x150.webp 150w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit-768x768.webp 768w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit-12x12.webp 12w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit-600x600.webp 600w, https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/RapidCharge-30kW-EV-DC-Charger-Module-\u2013-High-Power-Fast-Charging-Unit-100x100.webp 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1972299753 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<h2 data-start=\"1801\" data-end=\"1907\">\u26a1 <strong data-start=\"1805\" data-end=\"1905\">Por qu\u00e9 el m\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos Energysplendor de 30 kW se destaca en la industria mundial de la carga r\u00e1pida<\/strong><\/h2>\n<p data-start=\"1908\" data-end=\"2250\">Si tu empresa se dedica a la fabricaci\u00f3n <a href=\"https:\/\/energy-splendor.com\/es_cl\/Wholesale\/level-3-ev-chargers\/\">Cargadores r\u00e1pidos para veh\u00edculos el\u00e9ctricos<\/a>, ya sea ampliando la infraestructura p\u00fablica de recarga u ofreciendo soluciones de recarga para veh\u00edculos el\u00e9ctricos, el <strong data-start=\"2049\" data-end=\"2078\">M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW<\/strong> es un componente fundamental. Su dise\u00f1o integra componentes electr\u00f3nicos de alta calidad, una arquitectura t\u00e9rmica robusta, una eficiencia l\u00edder en la industria y protecciones que cumplen con los est\u00e1ndares internacionales.<\/p>\n<p data-start=\"2252\" data-end=\"2390\">A continuaci\u00f3n se presentan las principales ventajas que hacen que este <strong data-start=\"2296\" data-end=\"2329\">M\u00f3dulo de potencia de carga de 30 kW CC<\/strong> una opci\u00f3n preferida en las instalaciones de recarga comercial:<\/p>\n<h3 data-start=\"2392\" data-end=\"2466\">\u2714 <strong data-start=\"2398\" data-end=\"2464\">Alta eficiencia &gt; 95,51 TP3T \u2014 Menor desperdicio de energ\u00eda y menores costos operativos<\/strong><\/h3>\n<p data-start=\"2467\" data-end=\"2769\">El m\u00f3dulo ofrece una eficiencia excepcional a plena carga, superior al 95,51 TP3T, lo que reduce significativamente la p\u00e9rdida de potencia y mejora el ahorro energ\u00e9tico a largo plazo. Para los operadores comerciales y <a href=\"https:\/\/energy-splendor.com\/es_cl\/Wholesale\/dc-ev-chargers\/\">Fabricantes de cargadores r\u00e1pidos de corriente continua<\/a>, un sistema de alta eficiencia <strong data-start=\"2685\" data-end=\"2717\">M\u00f3dulo de potencia para cargador r\u00e1pido de corriente continua<\/strong> reduce directamente el costo de la electricidad y mejora el retorno de la inversi\u00f3n.<\/p>\n<h3 data-start=\"2771\" data-end=\"2841\">\u2714 <strong data-start=\"2777\" data-end=\"2839\">Amplio rango de salida \u2014 Compatible con plataformas de veh\u00edculos el\u00e9ctricos de 100 a 1000 V<\/strong><\/h3>\n<p data-start=\"2842\" data-end=\"3088\">El <strong data-start=\"2846\" data-end=\"2873\">M\u00f3dulo de carga r\u00e1pida para veh\u00edculos el\u00e9ctricos<\/strong> Admite una salida de 100 V a 1000 V, lo que permite la compatibilidad tanto con veh\u00edculos el\u00e9ctricos de 400 V como con la nueva generaci\u00f3n de plataformas ultrarr\u00e1pidas para veh\u00edculos el\u00e9ctricos de 800 V. Esto garantiza la compatibilidad universal con casi todos los modelos de veh\u00edculos el\u00e9ctricos en los mercados mundiales.<\/p>\n<h3 data-start=\"3090\" data-end=\"3137\">\u2714 <strong data-start=\"3096\" data-end=\"3135\">Ampliaci\u00f3n en paralelo de hasta 60 m\u00f3dulos<\/strong><\/h3>\n<p data-start=\"3138\" data-end=\"3362\">Una de las principales ventajas de esto <strong data-start=\"3174\" data-end=\"3206\">m\u00f3dulo de carga comercial para veh\u00edculos el\u00e9ctricos<\/strong> es su escalabilidad modular. Cuando se combinan en paralelo, admite configuraciones de potencia que van desde los 30 kW hasta sistemas de carga r\u00e1pida de potencia ultraalta.<\/p>\n<h3 data-start=\"3364\" data-end=\"3418\">\u2714 <strong data-start=\"3370\" data-end=\"3416\">Protecci\u00f3n s\u00f3lida y monitoreo inteligente<\/strong><\/h3>\n<p data-start=\"3419\" data-end=\"3724\">Entre sus caracter\u00edsticas se incluyen protecci\u00f3n contra subtensi\u00f3n y sobretensi\u00f3n de entrada, protecci\u00f3n contra sobretensi\u00f3n de salida, protecci\u00f3n contra sobrecorriente, protecci\u00f3n contra cortocircuitos y protecci\u00f3n t\u00e9rmica con funciones de recuperaci\u00f3n autom\u00e1tica o manual. Estas medidas de seguridad avanzadas mejoran significativamente la seguridad y la confiabilidad en entornos de recarga p\u00fablicos.<\/p>\n<h3 data-start=\"3726\" data-end=\"3769\">\u2714 <strong data-start=\"3732\" data-end=\"3767\">Dise\u00f1ado para entornos hostiles<\/strong><\/h3>\n<p data-start=\"3770\" data-end=\"3977\">Con un rango de temperatura de funcionamiento extremadamente amplio (de \u201340 \u00b0C a +75 \u00b0C), este <strong data-start=\"3844\" data-end=\"3873\">M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW<\/strong> funciona de manera confiable en desiertos calurosos, climas fr\u00edos, regiones costeras y entornos urbanos con mucho tr\u00e1fico.<\/p>\n<hr data-start=\"3979\" data-end=\"3982\" \/>\n<h2 data-start=\"3984\" data-end=\"4067\">\ud83d\udcd0 <strong data-start=\"3989\" data-end=\"4065\">Especificaciones t\u00e9cnicas del m\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos Energysplendor de 30 kW<\/strong><\/h2>\n<p data-start=\"4068\" data-end=\"4165\">A continuaci\u00f3n se presenta un resumen completo de las especificaciones t\u00e9cnicas del <strong data-start=\"4131\" data-end=\"4164\">M\u00f3dulo de potencia de carga de 30 kW CC<\/strong>:<\/p>\n<h3 data-start=\"4167\" data-end=\"4197\"><strong data-start=\"4171\" data-end=\"4195\">Especificaciones b\u00e1sicas<\/strong><\/h3>\n<ul data-start=\"4198\" data-end=\"4527\">\n<li data-start=\"4198\" data-end=\"4247\">\n<p data-start=\"4200\" data-end=\"4247\">Dimensiones: <strong data-start=\"4212\" data-end=\"4245\">85 mm (alto) \u00d7 360 mm (ancho) \u00d7 459 mm (profundidad)<\/strong><\/p>\n<\/li>\n<li data-start=\"4248\" data-end=\"4270\">\n<p data-start=\"4250\" data-end=\"4270\">Peso: <strong data-start=\"4258\" data-end=\"4268\">\u226420 kg<\/strong><\/p>\n<\/li>\n<li data-start=\"4271\" data-end=\"4309\">\n<p data-start=\"4273\" data-end=\"4309\">Eficiencia (a plena carga): <strong data-start=\"4297\" data-end=\"4307\">&gt;95,5%<\/strong><\/p>\n<\/li>\n<li data-start=\"4310\" data-end=\"4349\">\n<p data-start=\"4312\" data-end=\"4349\">Consumo de energ\u00eda en modo de espera: <strong data-start=\"4339\" data-end=\"4347\">&lt;13W<\/strong><\/p>\n<\/li>\n<li data-start=\"4350\" data-end=\"4392\">\n<p data-start=\"4352\" data-end=\"4392\">M\u00e9todo de enfriamiento: <strong data-start=\"4368\" data-end=\"4390\">Enfriamiento por aire forzado<\/strong><\/p>\n<\/li>\n<li data-start=\"4393\" data-end=\"4432\">\n<p data-start=\"4395\" data-end=\"4432\">Protocolo de comunicaci\u00f3n: <strong data-start=\"4419\" data-end=\"4430\">Bus CAN<\/strong><\/p>\n<\/li>\n<li data-start=\"4433\" data-end=\"4469\">\n<p data-start=\"4435\" data-end=\"4469\">N\u00famero m\u00e1ximo de m\u00f3dulos en paralelo: <strong data-start=\"4457\" data-end=\"4467\">\u226460 unidades<\/strong><\/p>\n<\/li>\n<li data-start=\"4470\" data-end=\"4527\">\n<p data-start=\"4472\" data-end=\"4527\">Indicadores: Verde (normal), Amarillo (alarma), Rojo (fallo)<\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"4529\" data-end=\"4532\" \/>\n<h3 data-start=\"4534\" data-end=\"4565\"><strong data-start=\"4538\" data-end=\"4563\">Caracter\u00edsticas de entrada<\/strong><\/h3>\n<ul data-start=\"4566\" data-end=\"4729\">\n<li data-start=\"4566\" data-end=\"4624\">\n<p data-start=\"4568\" data-end=\"4624\">Voltaje de entrada: <strong data-start=\"4583\" data-end=\"4622\">285 V CA \u2013 475 V CA (trif\u00e1sico + tierra)<\/strong><\/p>\n<\/li>\n<li data-start=\"4625\" data-end=\"4652\">\n<p data-start=\"4627\" data-end=\"4652\">Corriente de entrada: <strong data-start=\"4642\" data-end=\"4650\">&lt;80A<\/strong><\/p>\n<\/li>\n<li data-start=\"4653\" data-end=\"4686\">\n<p data-start=\"4655\" data-end=\"4686\">Frecuencia de la red el\u00e9ctrica: <strong data-start=\"4671\" data-end=\"4684\">45 Hz\u201365 Hz<\/strong><\/p>\n<\/li>\n<li data-start=\"4687\" data-end=\"4714\">\n<p data-start=\"4689\" data-end=\"4714\">Factor de potencia: <strong data-start=\"4703\" data-end=\"4712\">\u22650,99<\/strong><\/p>\n<\/li>\n<li data-start=\"4715\" data-end=\"4729\">\n<p data-start=\"4717\" data-end=\"4729\">THD: <strong data-start=\"4722\" data-end=\"4729\">\u22645%<\/strong><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"4731\" data-end=\"4734\" \/>\n<h3 data-start=\"4736\" data-end=\"4768\"><strong data-start=\"4740\" data-end=\"4766\">Caracter\u00edsticas de salida<\/strong><\/h3>\n<ul data-start=\"4769\" data-end=\"5023\">\n<li data-start=\"4769\" data-end=\"4813\">\n<p data-start=\"4771\" data-end=\"4813\"><strong data-start=\"4771\" data-end=\"4811\">Potencia de salida: 30 kW a una tensi\u00f3n de salida \u2265 300 Vcc<\/strong><\/p>\n<\/li>\n<li data-start=\"4814\" data-end=\"4851\">\n<p data-start=\"4816\" data-end=\"4851\">Rango de voltaje: <strong data-start=\"4831\" data-end=\"4849\">100 V CC \u2013 1000 V CC<\/strong><\/p>\n<\/li>\n<li data-start=\"4852\" data-end=\"4882\">\n<p data-start=\"4854\" data-end=\"4882\">Rango de corriente: <strong data-start=\"4869\" data-end=\"4880\">0 A\u2013100 A<\/strong><\/p>\n<\/li>\n<li data-start=\"4883\" data-end=\"4915\">\n<p data-start=\"4885\" data-end=\"4915\">Precisi\u00f3n de tensi\u00f3n: <strong data-start=\"4903\" data-end=\"4913\">\u2264\u00b10,5%<\/strong><\/p>\n<\/li>\n<li data-start=\"4916\" data-end=\"4946\">\n<p data-start=\"4918\" data-end=\"4946\">Precisi\u00f3n de la corriente: <strong data-start=\"4936\" data-end=\"4944\">\u2264\u00b11%<\/strong><\/p>\n<\/li>\n<li data-start=\"4947\" data-end=\"4986\">\n<p data-start=\"4949\" data-end=\"4986\">Desequilibrio en el reparto de corriente: <strong data-start=\"4976\" data-end=\"4984\">\u2264\u00b13%<\/strong><\/p>\n<\/li>\n<li data-start=\"4987\" data-end=\"5023\">\n<p data-start=\"4989\" data-end=\"5023\">Valor m\u00e1ximo de la tensi\u00f3n de ondulaci\u00f3n: <strong data-start=\"5016\" data-end=\"5023\">\u22641%<\/strong><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"5025\" data-end=\"5028\" \/>\n<h3 data-start=\"5030\" data-end=\"5068\"><strong data-start=\"5034\" data-end=\"5066\">Especificaciones ambientales<\/strong><\/h3>\n<ul data-start=\"5069\" data-end=\"5297\">\n<li data-start=\"5069\" data-end=\"5114\">\n<p data-start=\"5071\" data-end=\"5114\">Temperatura de funcionamiento: <strong data-start=\"5094\" data-end=\"5112\">De \u201340 \u00b0C a +75 \u00b0C<\/strong><\/p>\n<\/li>\n<li data-start=\"5115\" data-end=\"5158\">\n<p data-start=\"5117\" data-end=\"5158\">Temperatura de almacenamiento: <strong data-start=\"5138\" data-end=\"5156\">De \u201340 \u00b0C a +75 \u00b0C<\/strong><\/p>\n<\/li>\n<li data-start=\"5159\" data-end=\"5210\">\n<p data-start=\"5161\" data-end=\"5210\">Humedad relativa: <strong data-start=\"5180\" data-end=\"5208\">\u226495% RH (sin condensaci\u00f3n)<\/strong><\/p>\n<\/li>\n<li data-start=\"5211\" data-end=\"5270\">\n<p data-start=\"5213\" data-end=\"5270\">Altitud: <strong data-start=\"5223\" data-end=\"5268\">\u22642000 m a plena potencia; reducci\u00f3n de potencia por encima de los 1000 m<\/strong><\/p>\n<\/li>\n<li data-start=\"5271\" data-end=\"5297\">\n<p data-start=\"5273\" data-end=\"5297\">MTBF: <strong data-start=\"5279\" data-end=\"5297\">&gt;500 000 horas<\/strong><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"5299\" data-end=\"5302\" \/>\n<h3 data-start=\"5304\" data-end=\"5339\"><strong data-start=\"5308\" data-end=\"5337\">Especificaciones de protecci\u00f3n<\/strong><\/h3>\n<ul data-start=\"5340\" data-end=\"5528\">\n<li data-start=\"5340\" data-end=\"5388\">\n<p data-start=\"5342\" data-end=\"5388\">Sobretensi\u00f3n o subtensi\u00f3n de entrada: <strong data-start=\"5369\" data-end=\"5386\">Recuperaci\u00f3n autom\u00e1tica<\/strong><\/p>\n<\/li>\n<li data-start=\"5389\" data-end=\"5432\">\n<p data-start=\"5391\" data-end=\"5432\">Sobretensi\u00f3n de salida: <strong data-start=\"5411\" data-end=\"5430\">Recuperaci\u00f3n manual<\/strong><\/p>\n<\/li>\n<li data-start=\"5433\" data-end=\"5485\">\n<p data-start=\"5435\" data-end=\"5485\">Sobrecorriente \/ Cortocircuito: <strong data-start=\"5464\" data-end=\"5483\">Recuperaci\u00f3n manual<\/strong><\/p>\n<\/li>\n<li data-start=\"5486\" data-end=\"5528\">\n<p data-start=\"5488\" data-end=\"5528\">Sobretemperatura: <strong data-start=\"5506\" data-end=\"5528\">Recuperaci\u00f3n autom\u00e1tica<\/strong><\/p>\n<\/li>\n<\/ul>\n<hr data-start=\"5530\" data-end=\"5533\" \/>\n<h2 data-start=\"5535\" data-end=\"5594\">\ud83c\udf0d <strong data-start=\"5540\" data-end=\"5592\">Dise\u00f1ado para redes globales de recarga de veh\u00edculos el\u00e9ctricos comerciales<\/strong><\/h2>\n<p data-start=\"5595\" data-end=\"5653\">El <strong data-start=\"5599\" data-end=\"5628\">M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW<\/strong> se utiliza ampliamente en:<\/p>\n<ul data-start=\"5654\" data-end=\"5947\">\n<li data-start=\"5654\" data-end=\"5690\">\n<p data-start=\"5656\" data-end=\"5690\">Estaciones p\u00fablicas de carga r\u00e1pida de corriente continua<\/p>\n<\/li>\n<li data-start=\"5691\" data-end=\"5724\">\n<p data-start=\"5693\" data-end=\"5724\">Centros de recarga r\u00e1pida para veh\u00edculos el\u00e9ctricos en autopistas<\/p>\n<\/li>\n<li data-start=\"5725\" data-end=\"5764\">\n<p data-start=\"5727\" data-end=\"5764\">Sistemas de cobro de estacionamiento comercial<\/p>\n<\/li>\n<li data-start=\"5765\" data-end=\"5793\">\n<p data-start=\"5767\" data-end=\"5793\">Estaciones de recarga para flotas de veh\u00edculos el\u00e9ctricos<\/p>\n<\/li>\n<li data-start=\"5794\" data-end=\"5834\">\n<p data-start=\"5796\" data-end=\"5834\">Estaciones de recarga para veh\u00edculos el\u00e9ctricos de taxi y reparto<\/p>\n<\/li>\n<li data-start=\"5835\" data-end=\"5874\">\n<p data-start=\"5837\" data-end=\"5874\">Cargadores r\u00e1pidos para comunidades residenciales<\/p>\n<\/li>\n<li data-start=\"5875\" data-end=\"5905\">\n<p data-start=\"5877\" data-end=\"5905\">Sitios de conversi\u00f3n de veh\u00edculos de gasolina a el\u00e9ctricos<\/p>\n<\/li>\n<li data-start=\"5906\" data-end=\"5947\">\n<p data-start=\"5908\" data-end=\"5947\">Proyectos de infraestructura para veh\u00edculos el\u00e9ctricos en ciudades inteligentes<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"5949\" data-end=\"6256\">Esto <strong data-start=\"5954\" data-end=\"5986\">m\u00f3dulo de carga comercial para veh\u00edculos el\u00e9ctricos<\/strong> est\u00e1 dise\u00f1ado para cumplir con las estrictas exigencias de desempe\u00f1o de los mercados internacionales, entre los que se incluyen:<br data-start=\"6075\" data-end=\"6078\" \/>\ud83c\udde7\ud83c\uddf7 Brasil | \ud83c\udde6\ud83c\uddf7 Argentina | \ud83c\uddfa\ud83c\uddf8 EE. UU. | \ud83c\udde8\ud83c\udde6 Canad\u00e1 | \ud83c\uddf2\ud83c\uddfd M\u00e9xico | \ud83c\uddfb\ud83c\uddea Venezuela<br data-start=\"6162\" data-end=\"6165\" \/>\ud83c\udde6\ud83c\uddfa Australia | \ud83c\udde9\ud83c\uddea Alemania | \ud83c\uddff\ud83c\udde6 Sud\u00e1frica | \ud83c\udde6\ud83c\uddea Emiratos \u00c1rabes Unidos | \ud83c\udf0e En todo el mundo<\/p>\n<p data-start=\"6258\" data-end=\"6433\">Ya seas un proveedor, un integrador, un contratista EPC o una f\u00e1brica que produce cargadores r\u00e1pidos de corriente continua, esto <strong data-start=\"6360\" data-end=\"6387\">M\u00f3dulo de carga r\u00e1pida para veh\u00edculos el\u00e9ctricos<\/strong> ofrece una flexibilidad y escalabilidad sin igual.<\/p>\n<hr data-start=\"6435\" data-end=\"6438\" \/>\n<h2 data-start=\"6440\" data-end=\"6521\">\ud83c\udfed <strong data-start=\"6445\" data-end=\"6519\">Energysplendor \u2013 Fabricante l\u00edder de m\u00f3dulos de potencia para cargadores r\u00e1pidos de corriente continua<\/strong><\/h2>\n<p data-start=\"6522\" data-end=\"6583\">Como fabricante mundial de EVSE, <strong data-start=\"6553\" data-end=\"6571\">Energysplendor<\/strong> establece lo siguiente:<\/p>\n<ul data-start=\"6584\" data-end=\"6772\">\n<li data-start=\"6584\" data-end=\"6613\">\n<p data-start=\"6586\" data-end=\"6613\">Producci\u00f3n directa de f\u00e1brica<\/p>\n<\/li>\n<li data-start=\"6614\" data-end=\"6641\">\n<p data-start=\"6616\" data-end=\"6641\">Suministro mayorista a nivel mundial<\/p>\n<\/li>\n<li data-start=\"6642\" data-end=\"6667\">\n<p data-start=\"6644\" data-end=\"6667\">Personalizaci\u00f3n OEM\/ODM<\/p>\n<\/li>\n<li data-start=\"6668\" data-end=\"6700\">\n<p data-start=\"6670\" data-end=\"6700\">Soluciones modulares de cargadores de corriente continua<\/p>\n<\/li>\n<li data-start=\"6701\" data-end=\"6734\">\n<p data-start=\"6703\" data-end=\"6734\">Soporte t\u00e9cnico de ingenier\u00eda<\/p>\n<\/li>\n<li data-start=\"6735\" data-end=\"6772\">\n<p data-start=\"6737\" data-end=\"6772\">Capacidad de producci\u00f3n a gran escala<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"6774\" data-end=\"7025\">Trabajamos con fabricantes de cargadores para veh\u00edculos el\u00e9ctricos, empresas de electr\u00f3nica de potencia, proyectos gubernamentales y operadores de redes de recarga de veh\u00edculos el\u00e9ctricos en todo el mundo. Nuestro <strong data-start=\"6915\" data-end=\"6944\">M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW<\/strong> goza de gran confianza por su estabilidad, durabilidad y rendimiento rentable.<\/p>\n<hr data-start=\"7027\" data-end=\"7030\" \/>\n<h2 data-start=\"7032\" data-end=\"7112\">\ud83d\udce9 <strong data-start=\"7037\" data-end=\"7110\">P\u00f3ngase en contacto con Energysplendor para pedidos al por mayor, proyectos OEM y dise\u00f1os personalizados<\/strong><\/h2>\n<p data-start=\"7113\" data-end=\"7349\">Si est\u00e1s buscando un servicio confiable <strong data-start=\"7143\" data-end=\"7172\">M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos de 30 kW<\/strong>, un sistema escalable <strong data-start=\"7185\" data-end=\"7217\">M\u00f3dulo de potencia para cargador r\u00e1pido de corriente continua<\/strong>, o como socio de suministro a largo plazo para soluciones de recarga de veh\u00edculos el\u00e9ctricos, Energysplendor ofrece soluciones personalizadas para todas las necesidades comerciales.<\/p>\n<p data-start=\"7351\" data-end=\"7582\">\u27a1 <strong data-start=\"7353\" data-end=\"7441\">Env\u00edenos los detalles de su proyecto para recibir una cotizaci\u00f3n r\u00e1pida y asesor\u00eda t\u00e9cnica.<\/strong><br data-start=\"7441\" data-end=\"7444\" \/>Energysplendor ofrece:<br data-start=\"7468\" data-end=\"7471\" \/>\u2714 Precios de f\u00e1brica y al por mayor<br data-start=\"7498\" data-end=\"7501\" \/>\u2714 Env\u00edos a todo el mundo<br data-start=\"7518\" data-end=\"7521\" \/>\u2714 Personalizaci\u00f3n y promoci\u00f3n de la marca<br data-start=\"7547\" data-end=\"7550\" \/>\u2714 Cooperaci\u00f3n en materia de suministro a largo plazo<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f280-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"280\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es_cl\/wp-json\/wp\/v2\/product\/1861#wpcf7-f280-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es_cl\/wp-json\/wp\/v2\/product\/1861#wpcf7-f280-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"280\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f280-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class='custom_contact_style'>\n\t<div class=\"row row-small\">\n\t\t<div class=\"col medium-6 small-12 large-6\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col medium-6 small-12 large-6\">\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class='cus_contact_form_bottom'>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class='cus_contact_form_bottom'>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Pa\u00eds\" value=\"\" type=\"text\" name=\"your-country\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tu mensaje *\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n\t<div style=\"margin-bottom:10px;\">\n\t\t<p><span class=\"wpcf7-form-control-wrap kc_captcha cf7ic-toggle\" data-name=\"kc_captcha\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"captcha-image\" style=\"display: none;\"><span class=\"cf7ic_instructions\">Please prove you are human by selecting the<span> flag<\/span>.<\/span><label><input aria-label=\"1\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path fill=\"currentColor\" d=\"M415 24c-53 0-103 42-127 65-24-23-74-65-127-65C70 24 16 77 16 166c0 72 67 133 69 135l187 181c9 8 23 8 32 0l187-180c2-3 69-64 69-136 0-89-54-142-145-142z\"\/><\/svg><\/label><label><input aria-label=\"2\" type=\"radio\" name=\"kc_captcha\" value=\"kc_human\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"currentColor\" d=\"M350 99c-54 0-98-35-166-35-25 0-47 4-68 12a56 56 0 004-24C118 24 95 1 66 0a56 56 0 00-34 102v386c0 13 11 24 24 24h16c13 0 24-11 24-24v-94c28-12 64-23 114-23 54 0 98 35 166 35 48 0 86-16 122-41 9-6 14-15 14-26V96c0-23-24-39-45-29-35 16-77 32-117 32z\"\/><\/svg><\/label><label><input aria-label=\"3\" type=\"radio\" name=\"kc_captcha\" value=\"bot\" \/><svg aria-hidden=\"true\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 512\"><path fill=\"currentColor\" d=\"M624 352h-16V244c0-13-5-25-14-34L494 110c-9-9-21-14-34-14h-44V48c0-26-21-48-48-48H48C22 0 0 22 0 48v320c0 27 22 48 48 48h16a96 96 0 00192 0h128a96 96 0 00192 0h48c9 0 16-7 16-16v-32c0-9-7-16-16-16zM160 464a48 48 0 110-96 48 48 0 010 96zm320 0a48 48 0 110-96 48 48 0 010 96zm80-208H416V144h44l100 100v12z\"\/><\/svg><\/label>\r\n    <\/span>\r\n    <span style=\"display:none\">\r\n        <input type=\"text\" name=\"kc_honeypot\">\r\n    <\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar mensaje\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es_cl\"\/><\/form>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Tipo de producto: M\u00f3dulo de potencia para cargador de CC de veh\u00edculos el\u00e9ctricos de 30 kW<br \/>\nPotencia de salida: 30 kW CC<br \/>\nVoltaje de entrada: 285\u2013475 V CA, trif\u00e1sico + PE<br \/>\nTensi\u00f3n de salida: 100\u20131000 V CC (por defecto: 200 V CC)<br \/>\nProtocolo de comunicaci\u00f3n: Bus CAN<br \/>\nM\u00e9todo de enfriamiento: Enfriamiento por aire forzado<br \/>\nEficiencia: &gt;95,51 TP3T a plena carga<br \/>\nNormas: IEC 61851, ISO 15118<br \/>\nCertificados: CE, RoHS, ISO 9001<\/p>\n<p data-start=\"82\" data-end=\"645\">En 2024, <strong data-start=\"91\" data-end=\"110\">Esplendor energ\u00e9tico<\/strong> Ha suministrado m\u00f3dulos de cargadores de CC para veh\u00edculos el\u00e9ctricos de 30 kW a fabricantes de sistemas de carga y a proyectos comerciales de veh\u00edculos el\u00e9ctricos en Estados Unidos, Canad\u00e1, Brasil, M\u00e9xico, Alemania, Australia, Sud\u00e1frica y los Emiratos \u00c1rabes Unidos. Dise\u00f1ado para cargadores de Nivel 3 de 60 kW a 360 kW, este m\u00f3dulo de 30 kW ofrece alta eficiencia, salida de corriente continua estable, control mediante bus CAN y funciones completas de protecci\u00f3n. Su dise\u00f1o compacto, su bajo nivel de ondulaci\u00f3n y la compatibilidad con hasta 60 m\u00f3dulos en paralelo garantizan una f\u00e1cil escalabilidad, un mantenimiento reducido y un funcionamiento confiable para sistemas de carga r\u00e1pida p\u00fablicos, de flotas y comerciales.<\/p>","protected":false},"featured_media":1862,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[235,15],"product_tag":[219,216,221,217,220,225,224,218,222,223],"class_list":["post-1861","product","type-product","status-publish","has-post-thumbnail","product_cat-ev-charger-module","product_cat-paper-box-for-food","product_tag-30kw-dc-charging-unit","product_tag-30kw-ev-dc-charger-module","product_tag-commercial-ev-charging-module","product_tag-dc-fast-charging-power-module","product_tag-electric-vehicle-charging-module","product_tag-energy-splendor-charger-module","product_tag-ev-charging-power-supply","product_tag-ev-fast-charger-module","product_tag-high-efficiency-dc-charger","product_tag-modular-ev-fast-charger","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PowerCore 30kW EV DC Charger Module | High-Efficiency Fast Charging Power Module | Energy Splendor<\/title>\n<meta name=\"description\" content=\"PowerCore 30kW EV DC Charger Module delivers stable, high-efficiency fast charging for commercial EV stations. Reliable power performance by Energy Splendor\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-splendor.com\/es_cl\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PowerCore 30kW EV DC Charger Module | High-Efficiency Fast Charging Power Module | Energy Splendor\" \/>\n<meta property=\"og:description\" content=\"PowerCore 30kW EV DC Charger Module delivers stable, high-efficiency fast charging for commercial EV stations. Reliable power performance by Energy Splendor\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-splendor.com\/es_cl\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/\" \/>\n<meta property=\"og:site_name\" content=\"3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-24T09:44:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/\",\"url\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/\",\"name\":\"PowerCore 30kW EV DC Charger Module | High-Efficiency Fast Charging Power Module | Energy Splendor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/energy-splendor.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp\",\"datePublished\":\"2025-12-12T09:21:04+00:00\",\"dateModified\":\"2025-12-24T09:44:48+00:00\",\"description\":\"PowerCore 30kW EV DC Charger Module delivers stable, high-efficiency fast charging for commercial EV stations. Reliable power performance by Energy Splendor\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CL\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/#primaryimage\",\"url\":\"https:\\\/\\\/energy-splendor.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp\",\"contentUrl\":\"https:\\\/\\\/energy-splendor.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp\",\"width\":800,\"height\":800,\"caption\":\"PowerCore 30kW EV DC Charger Module from Energysplendor \u2014 designed for global EV charging station manufacturers, distributors, and integrators seeking high-efficiency, stable fast-charging performance.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/manufacturer\\\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/energy-splendor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/energy-splendor.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PowerCore 30kW EV DC Charger Module \u2013 High-Efficiency Fast Charging Power Module\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energy-splendor.com\\\/#website\",\"url\":\"https:\\\/\\\/energy-splendor.com\\\/\",\"name\":\"3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor\",\"description\":\"Leading EV Charger Manufacturer &amp; Supplier in China \u2014 Global Supply, Customization &amp; Wholesale Service for AC &amp; DC Charging Solutions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/energy-splendor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos PowerCore de 30 kW | M\u00f3dulo de potencia de carga r\u00e1pida de alta eficiencia | Energy Splendor","description":"El m\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos PowerCore de 30 kW ofrece una carga r\u00e1pida, estable y de alta eficiencia para estaciones comerciales de veh\u00edculos el\u00e9ctricos. Rendimiento energ\u00e9tico confiable de Energy Splendor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-splendor.com\/es_cl\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/","og_locale":"es_ES","og_type":"article","og_title":"PowerCore 30kW EV DC Charger Module | High-Efficiency Fast Charging Power Module | Energy Splendor","og_description":"PowerCore 30kW EV DC Charger Module delivers stable, high-efficiency fast charging for commercial EV stations. Reliable power performance by Energy Splendor","og_url":"https:\/\/energy-splendor.com\/es_cl\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/","og_site_name":"3.5kW\u2013900kW EV Charger Manufacturer | Portable, Wall-Mounted &amp; DC Fast Charging Stations | Energy Splendor","article_modified_time":"2025-12-24T09:44:48+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo estimado de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/","url":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/","name":"M\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos PowerCore de 30 kW | M\u00f3dulo de potencia de carga r\u00e1pida de alta eficiencia | Energy Splendor","isPartOf":{"@id":"https:\/\/energy-splendor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/#primaryimage"},"image":{"@id":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/#primaryimage"},"thumbnailUrl":"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp","datePublished":"2025-12-12T09:21:04+00:00","dateModified":"2025-12-24T09:44:48+00:00","description":"El m\u00f3dulo de carga de CC para veh\u00edculos el\u00e9ctricos PowerCore de 30 kW ofrece una carga r\u00e1pida, estable y de alta eficiencia para estaciones comerciales de veh\u00edculos el\u00e9ctricos. Rendimiento energ\u00e9tico confiable de Energy Splendor","breadcrumb":{"@id":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/#breadcrumb"},"inLanguage":"es-CL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/"]}]},{"@type":"ImageObject","inLanguage":"es-CL","@id":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/#primaryimage","url":"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp","contentUrl":"https:\/\/energy-splendor.com\/wp-content\/uploads\/2025\/12\/PowerCore-30kW-EV-DC-Charger-Module-\u2013-High-Efficiency-Fast-Charging-Power-Module.webp","width":800,"height":800,"caption":"PowerCore 30kW EV DC Charger Module from Energysplendor \u2014 designed for global EV charging station manufacturers, distributors, and integrators seeking high-efficiency, stable fast-charging performance."},{"@type":"BreadcrumbList","@id":"https:\/\/energy-splendor.com\/manufacturer\/powercore-30kw-ev-dc-charger-module-high-efficiency-fast-charging-power-module\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-splendor.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/energy-splendor.com\/shop\/"},{"@type":"ListItem","position":3,"name":"PowerCore 30kW EV DC Charger Module \u2013 High-Efficiency Fast Charging Power Module"}]},{"@type":"WebSite","@id":"https:\/\/energy-splendor.com\/#website","url":"https:\/\/energy-splendor.com\/","name":"Fabricante de cargadores para veh\u00edculos el\u00e9ctricos de 3,5 kW a 900 kW | Estaciones de carga port\u00e1tiles, de pared y de carga r\u00e1pida de CC | Energy Splendor","description":"Fabricante y proveedor l\u00edder de cargadores para veh\u00edculos el\u00e9ctricos en China: suministro global, personalizaci\u00f3n y servicio mayorista de soluciones de carga de CA y CC.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-splendor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/product\/1861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/comments?post=1861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/media\/1862"}],"wp:attachment":[{"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/media?parent=1861"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/product_brand?post=1861"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/product_cat?post=1861"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/energy-splendor.com\/es_cl\/wp-json\/wp\/v2\/product_tag?post=1861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}